{"id":2851,"date":"2015-07-22T09:43:24","date_gmt":"2015-07-22T09:43:24","guid":{"rendered":"https:\/\/www.lyntik.co\/blog\/?p=306"},"modified":"2022-05-03T22:49:48","modified_gmt":"2022-05-03T22:49:48","slug":"que-es-una-declaracion-de-cambio","status":"publish","type":"post","link":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/","title":{"rendered":"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?"},"content":{"rendered":"<h2>Es un formato dise\u00f1ado por el <strong><a href=\"https:\/\/www.banrep.gov.co\/\" target=\"_blank\" rel=\"noopener noreferrer\">Banco de la Rep\u00fablica<\/a><\/strong> de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del <strong>mercado cambiario.<\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/h2>\n<p><span style=\"color: #098d94;\"><strong>\u00bfQu\u00e9 eventos pueden presentarse con una Declaraci\u00f3n de Cambio?<\/strong><\/span><\/p>\n<p>Hay 4 eventos que pueden presentarse con las <strong>Declaraciones de Cambio:<\/strong><\/p>\n<ul>\n<li>1. Inicial: Debe utilizarse cuando se realiza una operaci\u00f3n de compra o venta por primera vez.<\/li>\n<li>2. Devoluci\u00f3n: Debe utilizarse cuando los recursos girados o recibidos anteriormente a trav\u00e9s de una operaci\u00f3n inicial deben ser devueltos parcial o totalmente.<\/li>\n<li>3. Cambio: Debe utilizarse cuando la declaraci\u00f3n de cambio realizada inicialmente debe ser cambiada por otro tipo de declaraci\u00f3n.<\/li>\n<li>4. Modificaci\u00f3n: Debe utilizarse para corregir informaci\u00f3n de una declaraci\u00f3n de cambio inicial, siempre y cuando la adici\u00f3n o correcci\u00f3n no obedezca a datos de los documentos aduaneros.<\/li>\n<\/ul>\n<p><span style=\"color: #098d94;\"><strong>\u00bfCu\u00e1les son las fechas para presentar los formularios de Declaraciones de Cambio al Banco de la Rep\u00fablica?<\/strong><\/span><\/p>\n<p>Las operaciones del cambio se deben presentar al <a href=\"https:\/\/www.banrep.gov.co\/\" target=\"_blank\" rel=\"noopener\"><strong>Banco de la Republica<\/strong><\/a> en el transcurso del mes siguiente a la fecha de la operaci\u00f3n<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #098d94;\"><strong>\u00bfQu\u00e9 son los Informes de la DIAN?<\/strong><\/span><\/p>\n<p>Seg\u00fan la Resoluci\u00f3n No. 09147 del 14 de Agosto de 2006, los Titulares de <strong>Cuentas de Compensaci\u00f3n<\/strong> deber\u00e1n presentar trimestralmente a la Unidad Administrativa Especial Direcci\u00f3n de Impuestos y Aduanas Nacionales &#8211; <strong><a href=\"https:\/\/www.dian.gov.co\/\" target=\"_blank\" rel=\"noopener noreferrer\">DIAN<\/a><\/strong> la informaci\u00f3n de inter\u00e9s para este organismo relacionada con las operaciones extranjeras, ci\u00f1\u00e9ndose al calendario definido por esa entidad seg\u00fan el \u00faltimo d\u00edgito del NIT.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><span style=\"color: #098d94;\"><em><a style=\"color: #098d94;\" href=\"https:\/\/www.lyntik.co\/blog\/que-es-el-mercado-cambiario-y-como-administrar-una-cuenta-de-compensacion\/\">\u25ba Tambi\u00e9n puede le interesar: \u00bfQu\u00e9 es el Mercado Cambiario y como administrar una cuenta de compensaci\u00f3n?<\/a><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #098d94;\"><strong>\u00bfCu\u00e1les son las fechas para hacer los reportes a la DIAN?<\/strong><\/span><\/p>\n<p>El calendario de presentaci\u00f3n de los informes est\u00e1 definido de acuerdo al \u00faltimo d\u00edgito del NIT o c\u00e9dula del titular de las <strong>cuentas de compensaci\u00f3n.<\/strong><\/p>\n<ul>\n<li>1 y 2 El d\u00e9cimo (10) y und\u00e9cimo (11) d\u00eda h\u00e1bil de los meses de abril, julio, octubre y enero.<\/li>\n<li>3 y 4 El duod\u00e9cimo (12) y decimotercero (13) d\u00eda h\u00e1bil de los meses de abril, julio, octubre y enero.<\/li>\n<li>5 y 6 El decimocuarto (14) y decimoquinto (15) d\u00eda h\u00e1bil de los meses de abril, julio, octubre y enero.<\/li>\n<li>7 y 8 El decimosexto (16) y decimos\u00e9ptimo (17) d\u00eda h\u00e1bil de los meses de abril, julio, octubre y enero.<\/li>\n<li>9 y 0 El decimoctavo (18) y decimonoveno (19) d\u00eda h\u00e1bil de los meses de abril, julio, octubre y enero.<\/li>\n<\/ul>\n<p><span style=\"color: #098d94;\"><strong>\u00bfLos informes que se presentan a la DIAN son diferentes a los que se presentan al Banco de la Rep\u00fablica?<\/strong><\/span><\/p>\n<p>Si, al <strong>Banco de la rep\u00fablica<\/strong> se reportan los formularios 1: Importaciones de Bienes, 2: Exportaciones de bienes, 3: Endeudamiento externo, 4: Inversiones Internacionales y 5: Servicios, transferencias y otros para ser diligenciados por el cliente y el F10.<\/p>\n<p>A la <strong>DIAN <\/strong>son reportados los formatos 1059, 1060, 1061,1062 y 1067.<\/p>\n<p><strong>\u00bfCu\u00e1les son los Formatos de la DIAN que puedo generar?<\/strong><\/p>\n<ul>\n<li><strong>Formulario 1059:<\/strong> Informe de datos de declaraci\u00f3n de cambio por Importaci\u00f3n de Bienes<\/li>\n<\/ul>\n<p>(Formulario 1)<\/p>\n<ul>\n<li><strong>Formularios 1060:<\/strong> Informe de datos de declaraci\u00f3n de cambio por Exportaci\u00f3n de Bienes<\/li>\n<\/ul>\n<p>(Formulario 2)<\/p>\n<ul>\n<li><strong>Formulario 1061<\/strong>: Informe de datos de declaraci\u00f3n de cambio por Endeudamiento Externo<\/li>\n<\/ul>\n<p>(Formulario 3)<\/p>\n<ul>\n<li><strong>Formulario 1062:<\/strong> Informe de datos de declaraci\u00f3n de cambio por Servicios, Transferencias y otros conceptos (Formulario 5) para ser diligenciados por el cliente.<\/li>\n<li><strong> Formulario 1067<\/strong>: Informe de Complemento de Datos Faltantes Declaraciones de Cambio<\/li>\n<\/ul>\n<p>(Formularios 1 y 2)<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">\u00bfTu empresa realiza operaciones de comercio exterior a trav\u00e9s\u00a0de cuentas de compensaci\u00f3n? <a href=\"https:\/\/www.akountik.com\/\" target=\"_blank\" rel=\"noopener\">\u00a1AKOUNTIK ES PARA TI!<\/a><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0099a8;\"><strong>Mira la versi\u00f3n SlideShare:<\/strong><\/span><\/p>\n<p><iframe style=\"border: 1px solid #CCC; border-width: 1px; margin-bottom: 5px; max-width: 100%;\" src=\"\/\/www.slideshare.net\/slideshow\/embed_code\/key\/1SD18kz8HYQy03\" width=\"425\" height=\"355\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"> <\/iframe><\/p>\n<div style=\"margin-bottom: 5px;\"><strong> <a title=\"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?\" href=\"\/\/www.slideshare.net\/Lyntiksas\/qu-es-una-declaracin-de-cambio\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?<\/a> <\/strong> from <strong><a href=\"\/\/www.slideshare.net\/Lyntiksas\" target=\"_blank\" rel=\"noopener noreferrer\">Lyntik<\/a><\/strong><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":2100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio? - Blog lyntik<\/title>\n<meta name=\"description\" content=\"Una de claraci\u00f3n de cambio es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del mercado cambiario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio? - Blog lyntik\" \/>\n<meta property=\"og:description\" content=\"Una de claraci\u00f3n de cambio es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del mercado cambiario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog lyntik\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-22T09:43:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-03T22:49:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lyntik.co\/blog\/wp-content\/uploads\/2015\/07\/lyntik-que-es-una-declaracion-de-cambio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lyntik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lyntik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/\"},\"author\":{\"name\":\"lyntik\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"headline\":\"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?\",\"datePublished\":\"2015-07-22T09:43:24+00:00\",\"dateModified\":\"2022-05-03T22:49:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/\"},\"wordCount\":613,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/lyntik-que-es-una-declaracion-de-cambio.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/\",\"name\":\"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio? - Blog lyntik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/lyntik-que-es-una-declaracion-de-cambio.jpg\",\"datePublished\":\"2015-07-22T09:43:24+00:00\",\"dateModified\":\"2022-05-03T22:49:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"description\":\"Una de claraci\u00f3n de cambio es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del mercado cambiario.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/lyntik-que-es-una-declaracion-de-cambio.jpg\",\"contentUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/lyntik-que-es-una-declaracion-de-cambio.jpg\",\"width\":800,\"height\":600,\"caption\":\"Que es una declaraci\u00f3n de cambio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2015\\\/07\\\/que-es-una-declaracion-de-cambio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\",\"name\":\"Blog lyntik\",\"description\":\"Blog lyntik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\",\"name\":\"lyntik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"contentUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"caption\":\"lyntik\"},\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/author\\\/lyntik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio? - Blog lyntik","description":"Una de claraci\u00f3n de cambio es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del mercado cambiario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio? - Blog lyntik","og_description":"Una de claraci\u00f3n de cambio es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del mercado cambiario.","og_url":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/","og_site_name":"Blog lyntik","article_published_time":"2015-07-22T09:43:24+00:00","article_modified_time":"2022-05-03T22:49:48+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/lyntik.co\/blog\/wp-content\/uploads\/2015\/07\/lyntik-que-es-una-declaracion-de-cambio.jpg","type":"image\/jpeg"}],"author":"lyntik","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lyntik","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#article","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/"},"author":{"name":"lyntik","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"headline":"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?","datePublished":"2015-07-22T09:43:24+00:00","dateModified":"2022-05-03T22:49:48+00:00","mainEntityOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/"},"wordCount":613,"commentCount":0,"image":{"@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/lyntik.co\/blog\/wp-content\/uploads\/2015\/07\/lyntik-que-es-una-declaracion-de-cambio.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/","url":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/","name":"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio? - Blog lyntik","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#primaryimage"},"image":{"@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/lyntik.co\/blog\/wp-content\/uploads\/2015\/07\/lyntik-que-es-una-declaracion-de-cambio.jpg","datePublished":"2015-07-22T09:43:24+00:00","dateModified":"2022-05-03T22:49:48+00:00","author":{"@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"description":"Una de claraci\u00f3n de cambio es un formato dise\u00f1ado por el Banco de la Rep\u00fablica de obligatoria presentaci\u00f3n para los residentes y no residentes que realicen en Colombia operaciones de cambio a trav\u00e9s del mercado cambiario.","breadcrumb":{"@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#primaryimage","url":"https:\/\/lyntik.co\/blog\/wp-content\/uploads\/2015\/07\/lyntik-que-es-una-declaracion-de-cambio.jpg","contentUrl":"https:\/\/lyntik.co\/blog\/wp-content\/uploads\/2015\/07\/lyntik-que-es-una-declaracion-de-cambio.jpg","width":800,"height":600,"caption":"Que es una declaraci\u00f3n de cambio"},{"@type":"BreadcrumbList","@id":"https:\/\/lyntik.co\/blog\/2015\/07\/que-es-una-declaracion-de-cambio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lyntik.co\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es una Declaraci\u00f3n de Cambio?"}]},{"@type":"WebSite","@id":"https:\/\/lyntik.co\/blog\/#website","url":"https:\/\/lyntik.co\/blog\/","name":"Blog lyntik","description":"Blog lyntik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyntik.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca","name":"lyntik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","url":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","contentUrl":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","caption":"lyntik"},"url":"https:\/\/lyntik.co\/blog\/author\/lyntik\/"}]}},"_links":{"self":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/comments?post=2851"}],"version-history":[{"count":1,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2851\/revisions"}],"predecessor-version":[{"id":5701,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2851\/revisions\/5701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/media\/2100"}],"wp:attachment":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/media?parent=2851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/categories?post=2851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/tags?post=2851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}