{"id":2877,"date":"2017-10-10T09:58:48","date_gmt":"2017-10-10T09:58:48","guid":{"rendered":"https:\/\/www.lyntik.co\/blog\/?p=527"},"modified":"2023-09-18T18:01:04","modified_gmt":"2023-09-18T18:01:04","slug":"minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros","status":"publish","type":"post","link":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/","title":{"rendered":"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg\" alt=\"\" width=\"877\" height=\"340\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007870;\"><strong>Destacados:<\/strong><\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #007870;\">El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #007870;\">En la norma propuesta se busca identificar cu\u00e1les personas jur\u00eddicas o veh\u00edculos de inversi\u00f3n quedar\u00edan excluidos puedan quedar excluidos de supervisi\u00f3n.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #007870;\">Se advierte por parte del Ministerio de Hacienda que esa norma aplicar\u00e1 cuando el tama\u00f1o de la entidad no sea significativo dentro del tama\u00f1o de la holding.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #007870;\">Adem\u00e1s, cuando el nivel de exposici\u00f3n de riesgo no tenga impacto significativo.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #007870;\">En la ma\u00f1ana de hoy, el superintendente financiero, Jorge Casta\u00f1o, le dijo a Valora Inversiones que el Gobierno tiene seis meses para reglamentar la ley de conglomerados financieros. El mercado, dijo, tendr\u00e1 otros seis meses para ajustarse a la norma.\u00a0<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #007870;\">El texto del proyecto de decreto puede consultarse <a style=\"color: #007870;\" href=\"https:\/\/www.minhacienda.gov.co\/HomeMinhacienda\/ShowProperty?nodeId=%2FOCS%2FP_MHCP_WCC-092427%2F%2FidcPrimaryFile&amp;revision=latestreleased\">aqu\u00ed<\/a>.<\/span><\/li>\n<\/ul>\n<p style=\"line-height: 13.5pt; background: white; margin: 0cm 0cm 15.0pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial',sans-serif; color: #007078;\">Contenido generado por Valora Inversiones, nuestros expertos en informaci\u00f3n de valor.<\/span><span style=\"font-size: 10.5pt; font-family: 'Arial',sans-serif; color: #007870;\">Fuente:\u00a0<\/span><a href=\"https:\/\/www.valorainversiones.com\/sitio\/index.php\"><span style=\"font-size: 10.5pt; font-family: 'Arial',sans-serif; color: #007870;\">https:\/\/www.valor<\/span><\/a><a href=\"https:\/\/www.valorainversiones.com\/sitio\/index.php\"><span style=\"font-size: 10.5pt; font-family: 'Arial',sans-serif; color: #007870;\">ainversiones.com\/sitio\/index.php<\/span><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Destacados: El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo. En la norma propuesta se busca identificar cu\u00e1les personas jur\u00eddicas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-2877","post","type-post","status-publish","format-standard","hentry","category-finanzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros - Blog lyntik<\/title>\n<meta name=\"description\" content=\"El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros - Blog lyntik\" \/>\n<meta property=\"og:description\" content=\"El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog lyntik\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-10T09:58:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T18:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg\" \/>\n<meta name=\"author\" content=\"lyntik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lyntik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/\"},\"author\":{\"name\":\"lyntik\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"headline\":\"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros\",\"datePublished\":\"2017-10-10T09:58:48+00:00\",\"dateModified\":\"2023-09-18T18:01:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/\"},\"wordCount\":168,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2017-09-04.jpg\",\"articleSection\":[\"Finanzas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/\",\"name\":\"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros - Blog lyntik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2017-09-04.jpg\",\"datePublished\":\"2017-10-10T09:58:48+00:00\",\"dateModified\":\"2023-09-18T18:01:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"description\":\"El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2017-09-04.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2017-09-04.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2017\\\/10\\\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\",\"name\":\"Blog lyntik\",\"description\":\"Blog lyntik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\",\"name\":\"lyntik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"contentUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"caption\":\"lyntik\"},\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/author\\\/lyntik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros - Blog lyntik","description":"El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/","og_locale":"es_ES","og_type":"article","og_title":"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros - Blog lyntik","og_description":"El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.","og_url":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/","og_site_name":"Blog lyntik","article_published_time":"2017-10-10T09:58:48+00:00","article_modified_time":"2023-09-18T18:01:04+00:00","og_image":[{"url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg","type":"","width":"","height":""}],"author":"lyntik","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lyntik","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#article","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/"},"author":{"name":"lyntik","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"headline":"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros","datePublished":"2017-10-10T09:58:48+00:00","dateModified":"2023-09-18T18:01:04+00:00","mainEntityOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/"},"wordCount":168,"commentCount":0,"image":{"@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg","articleSection":["Finanzas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/","url":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/","name":"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros - Blog lyntik","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#primaryimage"},"image":{"@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg","datePublished":"2017-10-10T09:58:48+00:00","dateModified":"2023-09-18T18:01:04+00:00","author":{"@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"description":"El proyecto del Gobierno estar\u00e1 abierto para comentarios hasta el 13 de octubre pr\u00f3ximo.","breadcrumb":{"@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#primaryimage","url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg","contentUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2017-09-04.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lyntik.co\/blog\/2017\/10\/minhacienda-publica-primer-proyecto-de-decreto-sobre-vigilancia-a-conglomerados-financieros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lyntik.co\/blog\/"},{"@type":"ListItem","position":2,"name":"MinHacienda publica primer proyecto de decreto sobre vigilancia a conglomerados financieros"}]},{"@type":"WebSite","@id":"https:\/\/lyntik.co\/blog\/#website","url":"https:\/\/lyntik.co\/blog\/","name":"Blog lyntik","description":"Blog lyntik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyntik.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca","name":"lyntik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","url":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","contentUrl":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","caption":"lyntik"},"url":"https:\/\/lyntik.co\/blog\/author\/lyntik\/"}]}},"_links":{"self":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/comments?post=2877"}],"version-history":[{"count":1,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2877\/revisions"}],"predecessor-version":[{"id":5675,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2877\/revisions\/5675"}],"wp:attachment":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/media?parent=2877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/categories?post=2877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/tags?post=2877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}