{"id":2887,"date":"2018-01-09T15:18:50","date_gmt":"2018-01-09T15:18:50","guid":{"rendered":"https:\/\/www.lyntik.co\/blog\/?p=742"},"modified":"2023-09-18T17:56:43","modified_gmt":"2023-09-18T17:56:43","slug":"premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street","status":"publish","type":"post","link":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/","title":{"rendered":"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg\" width=\"877\" height=\"340\" \/><\/p>\n<p><span style=\"color: #007078;\"><strong>ASIA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">El promedio de acciones japon\u00e9s Nikkei toc\u00f3 un m\u00e1ximo de 26 a\u00f1os el martes, impulsado por el avance de Wall Street durante un feriado en Jap\u00f3n, mientras que los t\u00edtulos de Fast Retailing escalaron por s\u00f3lidas ventas en diciembre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">El \u00edndice m\u00e1s amplio Topix termin\u00f3 con un avance de 0,5 por ciento, a 1.889,29 unidades, su nivel de cierre m\u00e1s alto desde junio de 1991.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">De su parte, las acciones chinas ampliaron una racha alcista el martes por octavo d\u00eda consecutivo, con importantes \u00edndices en m\u00e1ximos de seis semanas gracias al avance de los t\u00edtulos de empresas de consumo y vinculadas a la salud.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">El \u00edndice compuesto de Shangh\u00e1i cerr\u00f3 con un avance de 5,35 puntos, o un 0,16 por ciento, a 3.414,83 unidades.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">En lo que va del a\u00f1o, el \u00edndice de acciones de Shangh\u00e1i ha subido un 3,09 por ciento, el CSI300, un 3,9 por ciento, y el \u00edndice H-share, que cotiza en Hong Kong, un 4,5 por ciento.<\/span><\/p>\n<p><span style=\"color: #007078;\"><img decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/3_2018-01-09.jpg\" width=\"512\" height=\"250\" \/><\/span><\/p>\n<p><span style=\"color: #007078;\"><strong>EUROPA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">El Ibex trunc\u00f3 ayer el pleno de subidas en 2018, pero en la sesi\u00f3n de hoy se esfuerza en recuperar los avances y los m\u00e1ximos de dos meses. Valores como Repsol reciben el respaldo de los m\u00e1ximos que alcanza el precio del petr\u00f3leo. La correcci\u00f3n en el euro, por debajo de 1,20 d\u00f3lares, anima ligeramente al conjunto de las Bolsas europeas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Los mercados financieros enfr\u00edan la euforia con la que comenzaron 2018.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">El aceler\u00f3n de las primeras jornadas del a\u00f1o ha dado paso a una tregua, coincidiendo adem\u00e1s con una agenda financiera escasa de referencias de calado. En plena cuenta atr\u00e1s para el arranque de la nueva temporada de resultados empresariales, los inversores apenas tendr\u00e1n ocasi\u00f3n esta semana de revalidar su optimismo sobre la evoluci\u00f3n de la econom\u00eda como consecuencia de la ausencia de datos macro de peso. Uno de los m\u00e1s destacados ser\u00e1 el IPC de EEUU, que se conocer\u00e1 el pr\u00f3ximo viernes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Las Bolsas europeas imitan el freno de Wall Street, y se esfuerzan en evitar los n\u00fameros rojos. A su favor cuentan con el respiro que otorga el euro, por debajo de los 1,20 d\u00f3lares y m\u00e1s lejos de sus m\u00e1ximos de tres a\u00f1os. El Ftse brit\u00e1nico amaga con nuevos m\u00e1ximos hist\u00f3ricos, por encima de los 7.700 puntos, mientras que el Dax alem\u00e1n enfr\u00eda su asalto a r\u00e9cords, a la espera de mayores avances en las negociaciones para formar una gran coalici\u00f3n de Gobierno en Alemania entre conservadores y socialistas, el escenario m\u00e1s deseado por los analistas.<\/span><\/p>\n<p><span style=\"color: #007078;\"><img decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/wp-content\/uploads\/2020\/07\/4_2018-01-09.jpg\" width=\"512\" height=\"251\" \/><\/span><\/p>\n<p><span style=\"color: #007078;\"><strong>AM\u00c9RICA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">El martes, el d\u00f3lar se manten\u00eda en m\u00e1ximos de una semana frente a otras monedas importantes, ya que los inversores esperaban un d\u00eda ligero para los datos econ\u00f3micos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Los participantes del mercado har\u00e1n un balance de m\u00e1s datos del mercado laboral con la publicaci\u00f3n de las Ofertas de empleo y la Encuesta de rotaci\u00f3n laboral (JOLTS).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Luego del informe de empleo del viernes pasado que decepcion\u00f3 al consenso, pero a\u00fan mostraba un mercado laboral s\u00f3lido, la presidenta saliente de la Reserva Federal, Janet Yellen, cit\u00f3 a JOLTS al evaluar las condiciones del mercado laboral.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Los s\u00f3lidos fundamentos alentar\u00edan al banco central de los Estados Unidos a seguir adelante con el endurecimiento gradual de la pol\u00edtica monetaria este a\u00f1o a pesar de que la inflaci\u00f3n persiste por debajo de su objetivo del 2%.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Los mercados tienen un precio de 68% para el siguiente aumento de 25 puntos b\u00e1sicos en marzo, seg\u00fan la herramienta de monitoreo de tasas de Fed.<\/span><\/p>\n<p><span style=\"color: #007078;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/5_2018-01-09.jpg\" width=\"512\" height=\"477\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Los futuros de Wall Street marcan tendencia al alza.<\/span><\/p>\n<p><span style=\"color: #007078;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/wp-content\/uploads\/2020\/07\/6_2018-01-09.jpg\" width=\"412\" height=\"85\" \/><\/span><\/p>\n<p><span style=\"color: #007078;\"><strong>RESUMEN DE MERCADO<\/strong><\/span><\/p>\n<p><span style=\"color: #007078;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/wp-content\/uploads\/2020\/07\/7_2018-01-09.jpg\" width=\"512\" height=\"259\" \/><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #007078;\">Contenido generado por Valora Inversiones, nuestros expertos en informaci\u00f3n de valor.<\/span><\/p>\n<p><span style=\"color: #007078;\">Fuente:\u00a0<a href=\"https:\/\/www.valorainversiones.com\/sitio\/index.php\">https:\/\/ww<\/a><a href=\"https:\/\/www.valorainversiones.com\/sitio\/index.php\">w.valor<\/a><a href=\"https:\/\/www.valorainversiones.com\/sitio\/index.php\">ainversiones.com\/sitio\/index.php<\/a><\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>ASIA El promedio de acciones japon\u00e9s Nikkei toc\u00f3 un m\u00e1ximo de 26 a\u00f1os el martes, impulsado por el avance de Wall Street durante un feriado [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-2887","post","type-post","status-publish","format-standard","hentry","category-finanzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street - Blog lyntik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street - Blog lyntik\" \/>\n<meta property=\"og:description\" content=\"ASIA El promedio de acciones japon\u00e9s Nikkei toc\u00f3 un m\u00e1ximo de 26 a\u00f1os el martes, impulsado por el avance de Wall Street durante un feriado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog lyntik\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-09T15:18:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T17:56:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg\" \/>\n<meta name=\"author\" content=\"lyntik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lyntik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/\"},\"author\":{\"name\":\"lyntik\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"headline\":\"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street\",\"datePublished\":\"2018-01-09T15:18:50+00:00\",\"dateModified\":\"2023-09-18T17:56:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/\"},\"wordCount\":661,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-09.jpg\",\"articleSection\":[\"Finanzas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/\",\"name\":\"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street - Blog lyntik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-09.jpg\",\"datePublished\":\"2018-01-09T15:18:50+00:00\",\"dateModified\":\"2023-09-18T17:56:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-09.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-09.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\",\"name\":\"Blog lyntik\",\"description\":\"Blog lyntik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\",\"name\":\"lyntik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076\",\"contentUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076\",\"caption\":\"lyntik\"},\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/author\\\/lyntik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street - Blog lyntik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/","og_locale":"es_ES","og_type":"article","og_title":"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street - Blog lyntik","og_description":"ASIA El promedio de acciones japon\u00e9s Nikkei toc\u00f3 un m\u00e1ximo de 26 a\u00f1os el martes, impulsado por el avance de Wall Street durante un feriado [&hellip;]","og_url":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/","og_site_name":"Blog lyntik","article_published_time":"2018-01-09T15:18:50+00:00","article_modified_time":"2023-09-18T17:56:43+00:00","og_image":[{"url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg","type":"","width":"","height":""}],"author":"lyntik","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lyntik","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#article","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/"},"author":{"name":"lyntik","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"headline":"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street","datePublished":"2018-01-09T15:18:50+00:00","dateModified":"2023-09-18T17:56:43+00:00","mainEntityOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/"},"wordCount":661,"commentCount":0,"image":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg","articleSection":["Finanzas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/","url":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/","name":"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street - Blog lyntik","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#primaryimage"},"image":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg","datePublished":"2018-01-09T15:18:50+00:00","dateModified":"2023-09-18T17:56:43+00:00","author":{"@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"breadcrumb":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#primaryimage","url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg","contentUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-09.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/premercado-bolsas-mundiales-suben-siguiendo-tendencia-wall-street\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lyntik.co\/blog\/"},{"@type":"ListItem","position":2,"name":"Premercado | Bolsas mundiales suben siguiendo tendencia de Wall Street"}]},{"@type":"WebSite","@id":"https:\/\/lyntik.co\/blog\/#website","url":"https:\/\/lyntik.co\/blog\/","name":"Blog lyntik","description":"Blog lyntik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyntik.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca","name":"lyntik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076","url":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076","contentUrl":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076","caption":"lyntik"},"url":"https:\/\/lyntik.co\/blog\/author\/lyntik\/"}]}},"_links":{"self":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/comments?post=2887"}],"version-history":[{"count":1,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2887\/revisions"}],"predecessor-version":[{"id":5664,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2887\/revisions\/5664"}],"wp:attachment":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/media?parent=2887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/categories?post=2887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/tags?post=2887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}