{"id":2895,"date":"2018-01-22T17:08:02","date_gmt":"2018-01-22T17:08:02","guid":{"rendered":"https:\/\/www.lyntik.co\/blog\/?p=769"},"modified":"2023-09-18T17:35:38","modified_gmt":"2023-09-18T17:35:38","slug":"769-2","status":"publish","type":"post","link":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/","title":{"rendered":"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg\" width=\"877\" height=\"340\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">La valorizaci\u00f3n del 3% que ha registrado el peso colombiano a inicios de 2018 y que lo ha convertido en una de las divisas emergentes con mejor rendimiento en 2018 parece desvanecerse, se\u00f1ala un informe de la comisionista de bolsa Acciones y Valores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">En el an\u00e1lisis se indica que, si bien el rally que ha registrado la moneda ha sido tan sorprendente como inesperado, se explica principalmente por la valorizaci\u00f3n del petr\u00f3leo, que ha registrado una ganancia cercana a los US$20 por barril desde mediados de 2017.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Otras razones que habr\u00edan motivado las ganancias en el peso, seg\u00fan la firma, tienen que ver con la intenci\u00f3n de las Empresas P\u00fablicas de Medell\u00edn de comprar una participaci\u00f3n controladora en Gas Natural SA ESP, que podr\u00eda requerir deuda externa por un monto cercano los US$700 millones, as\u00ed como la monetizaci\u00f3n que habr\u00edan hecho algunos grandes empresarios para atender el calendario tributario, los cuales habr\u00edan presionado temporalmente la moneda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">De cara al futuro cercano, la firma sostiene que una disminuci\u00f3n de los flujos estacionales, as\u00ed como un menor atractivo del carry trade y un estancamiento en el precio del petr\u00f3leo podr\u00eda hacer retroceder la moneda, en el entendido que la cotizaci\u00f3n enfrenta una barrera t\u00e9cnica cercana al nivel de $2.800, nivel que ha bloqueado apreciaciones adicionales desde octubre de 2015.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">\u201cEn el futuro cercano, estimamos que las perspectivas de sobreoferta en el petr\u00f3leo dadas a conocer recientemente por la Agencia Internacional de Energ\u00eda, limitar\u00e1n valorizaciones adicionales en el precio del petr\u00f3leo a pesar que la temporada de frio contin\u00faa azotando los EE.UU. limitando los niveles de producci\u00f3n y agotando por nueve semanas consecutivas los inventarios\u201d, se detalla en el informe de la firma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #007078;\">Finalmente, Acciones y Valores espera que el debate electoral del 2018, tema que hist\u00f3ricamente afecta las monedas de la regi\u00f3n con cinco meses de anticipaci\u00f3n, hagan parte de los fundamentales debatidos por el mercado, limitando las valorizaciones observadas recientemente.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-22.jpg\" width=\"495\" height=\"414\" \/><\/p>\n<p><span style=\"color: #007078;\">Contenido generado por Valora Inversiones, nuestros expertos en informaci\u00f3n de valor.<\/span><\/p>\n<p><span style=\"color: #007078;\">Fuente:<\/span>\u00a0<a href=\"https:\/\/www.grupovalora.com.co\">www.grupovalora.com.co<\/a><\/p>\n<p align=\"center\">\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La valorizaci\u00f3n del 3% que ha registrado el peso colombiano a inicios de 2018 y que lo ha convertido en una de las divisas emergentes [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-2895","post","type-post","status-publish","format-standard","hentry","category-finanzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones - Blog lyntik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones - Blog lyntik\" \/>\n<meta property=\"og:description\" content=\"La valorizaci\u00f3n del 3% que ha registrado el peso colombiano a inicios de 2018 y que lo ha convertido en una de las divisas emergentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog lyntik\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-22T17:08:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T17:35:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg\" \/>\n<meta name=\"author\" content=\"lyntik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lyntik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/\"},\"author\":{\"name\":\"lyntik\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"headline\":\"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones\",\"datePublished\":\"2018-01-22T17:08:02+00:00\",\"dateModified\":\"2023-09-18T17:35:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/\"},\"wordCount\":376,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-18.jpg\",\"articleSection\":[\"Finanzas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/\",\"name\":\"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones - Blog lyntik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-18.jpg\",\"datePublished\":\"2018-01-22T17:08:02+00:00\",\"dateModified\":\"2023-09-18T17:35:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-18.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-01-18.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/01\\\/769-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\",\"name\":\"Blog lyntik\",\"description\":\"Blog lyntik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\",\"name\":\"lyntik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"contentUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421\",\"caption\":\"lyntik\"},\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/author\\\/lyntik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones - Blog lyntik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/","og_locale":"es_ES","og_type":"article","og_title":"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones - Blog lyntik","og_description":"La valorizaci\u00f3n del 3% que ha registrado el peso colombiano a inicios de 2018 y que lo ha convertido en una de las divisas emergentes [&hellip;]","og_url":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/","og_site_name":"Blog lyntik","article_published_time":"2018-01-22T17:08:02+00:00","article_modified_time":"2023-09-18T17:35:38+00:00","og_image":[{"url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg","type":"","width":"","height":""}],"author":"lyntik","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lyntik","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#article","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/"},"author":{"name":"lyntik","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"headline":"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones","datePublished":"2018-01-22T17:08:02+00:00","dateModified":"2023-09-18T17:35:38+00:00","mainEntityOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/"},"wordCount":376,"commentCount":0,"image":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg","articleSection":["Finanzas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/","url":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/","name":"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones - Blog lyntik","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#primaryimage"},"image":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg","datePublished":"2018-01-22T17:08:02+00:00","dateModified":"2023-09-18T17:35:38+00:00","author":{"@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"breadcrumb":{"@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#primaryimage","url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg","contentUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-01-18.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lyntik.co\/blog\/2018\/01\/769-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lyntik.co\/blog\/"},{"@type":"ListItem","position":2,"name":"Acciones y Valores pronostica retroceso del d\u00f3lar en Colombia por mercado de petr\u00f3leo y elecciones"}]},{"@type":"WebSite","@id":"https:\/\/lyntik.co\/blog\/#website","url":"https:\/\/lyntik.co\/blog\/","name":"Blog lyntik","description":"Blog lyntik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyntik.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca","name":"lyntik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","url":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","contentUrl":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1783671421","caption":"lyntik"},"url":"https:\/\/lyntik.co\/blog\/author\/lyntik\/"}]}},"_links":{"self":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/comments?post=2895"}],"version-history":[{"count":1,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2895\/revisions"}],"predecessor-version":[{"id":5657,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/2895\/revisions\/5657"}],"wp:attachment":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/media?parent=2895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/categories?post=2895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/tags?post=2895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}