{"id":4881,"date":"2018-03-14T15:16:28","date_gmt":"2018-03-14T15:16:28","guid":{"rendered":"https:\/\/www.lyntik.co\/blog\/?p=828"},"modified":"2023-09-18T17:29:05","modified_gmt":"2023-09-18T17:29:05","slug":"bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu","status":"publish","type":"post","link":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/","title":{"rendered":"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU."},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg\" width=\"877\" height=\"340\" \/><\/p>\n<p><span style=\"color: #007078;\"><strong>ASIA<\/strong><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Las principales bolsas de valores de la regi\u00f3n Asia-Pac\u00edfico cerraron este mi\u00e9rcoles a la baja, ante los temores de un cambio en la pol\u00edtica exterior de la Casa Blanca luego del despido del secretario estadounidense de Estado, Rex Tillerson, y en medio de conversaciones sobre fuertes aranceles de Estados Unidos contra China.<\/span><\/p>\n<p><span style=\"color: #007078;\">Las acciones mundiales cayeron por segundo d\u00eda consecutivo y el d\u00f3lar se mantuvo cerca de m\u00ednimos de una semana luego de que las amenazas del presidente Donald Trump de aplicar 60 mil millones de d\u00f3lares en aranceles a las importaciones chinas, recordaron a los inversionistas la amenaza al crecimiento econ\u00f3mico mundial.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Los temores de la guerra comercial eclipsaron los fuertes datos econ\u00f3micos de China que mostraron que la producci\u00f3n industrial se expandi\u00f3 a un ritmo sorprendentemente m\u00e1s r\u00e1pido a comienzos de a\u00f1o.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">La inversi\u00f3n en activos fijos tambi\u00e9n super\u00f3 los pron\u00f3sticos, mientras que las ventas minoristas mejoraron. El referencial CSI300 de las principales acciones que cotizan en los mercados de Shanghai y Shenzhen retrocedi\u00f3 0,44 %, mientras el \u00cdndice Compuesto de Shanghai 0,57 %.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">En el mercado cambiario, el d\u00f3lar se negociaba en torno a 106.58 unidades contra el yen. En el mercado de Singapur, el peso mexicano se cambiaba a 18.53 unidades por d\u00f3lar estadounidense.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\"><img decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.png\" width=\"512\" height=\"286\" \/><\/span><\/p>\n<p><span style=\"color: #007078;\"><strong>EUROPA<\/strong><\/span><\/p>\n<p><span style=\"color: #007078;\">Las principales bolsas europeas abrieron este mi\u00e9rcoles con comportamiento mixto, despu\u00e9s que una nueva reorganizaci\u00f3n del gobierno estadounidense gener\u00f3 preocupaciones sobre un enfoque unilateral para el comercio, la seguridad nacional y los asuntos exteriores.<\/span><\/p>\n<p><span style=\"color: #007078;\">El repentino despido del secretario de Estado de los Estados Unidos, Rex Tillerson, tom\u00f3 a algunos por sorpresa menos de una semana despu\u00e9s de que el principal asesor econ\u00f3mico, Gary Cohn, renunciara a la Casa Blanca.<\/span><\/p>\n<p><span style=\"color: #007078;\">La ca\u00edda de Tillerson gener\u00f3 preocupaciones sobre la nueva gu\u00eda en la Casa Blanca que podr\u00eda tomar una l\u00ednea m\u00e1s dura sobre el comercio, promoviendo la agenda del presidente Donald Trump de imponer aranceles. Trump nomin\u00f3 al director de la Agencia Central de Inteligencia (CIA), Mike Pompeo, un ex congresista que ha respaldado &#8220;rechazar la amenaza china &#8221; para reemplazar a Tillerson.<\/span><\/p>\n<p><span style=\"color: #007078;\">El cambio se produce cuando la administraci\u00f3n de Washington considera la aplicaci\u00f3n de aranceles sobre una amplia gama de importaciones chinas, en espec\u00edfico los bienes del sector tecnol\u00f3gico y telecomunicaciones, por valor de 60 mil millones de d\u00f3lares. Vuelve as\u00ed el temor a una guerra comercial, aunque los inversionistas a\u00fan observen los acontecimientos con cautela y con la idea de que el conflicto comercial generalizado no terminar\u00e1 por estallar.<\/span><\/p>\n<p><span style=\"color: #007078;\">El argumento es que las empresas chinas usan tecnolog\u00eda estadounidense para vender productos y servicios en Estados Unidos a un precio m\u00e1s bajo. Trump precisamente ayer vet\u00f3 la opa hostil de la empresa de Singapur Broadcom sobre la estadounidense Qualcomm por motivos de &#8220;seguridad nacional&#8221;.<\/span><\/p>\n<p><span style=\"color: #007078;\">En el mercado de divisas, el euro subi\u00f3 hoy en la negociaci\u00f3n europea del mercado de divisas y a las 7:00 GMT se cambiaba a 1.2397 d\u00f3lares frente a los 1.2395 d\u00f3lares a que se negociaba el martes a las 16:00 GMT.<\/span><\/p>\n<p><span style=\"color: #007078;\">El \u00edndice Stoxx Europe 600, que agrupa a las 600 compa\u00f1\u00edas m\u00e1s importantes que cotizan en los mercados de renta variable de 18 pa\u00edses europeos, bajaba a las 8:15 horas de Londres, 0,13 % para ubicarse en 379.09.<\/span><\/p>\n<p><span style=\"color: #007078;\">Por otro lado, el presidente del Banco Central Europeo, Mario Draghi, dijo el mi\u00e9rcoles que la autoridad monetaria de la zona euro a\u00fan necesitaba ver m\u00e1s evidencia de que la inflaci\u00f3n se estaba moviendo hacia el objetivo antes de considerar la eliminaci\u00f3n del est\u00edmulo monetario.<\/span><\/p>\n<p><span style=\"color: #007078;\">&#8220;Actualmente vemos que la inflaci\u00f3n converge hacia nuestro objetivo en el mediano plazo, y tenemos m\u00e1s confianza que en el pasado esta convergencia se cumplir\u00e1&#8221;, dijo Draghi en una conferencia el mi\u00e9rcoles. &#8220;Pero a\u00fan necesitamos ver m\u00e1s evidencia de que la din\u00e1mica de la inflaci\u00f3n avanza en la direcci\u00f3n correcta&#8221;, agreg\u00f3.<\/span><\/p>\n<p><span style=\"color: #007078;\">Draghi dej\u00f3 en claro que ser\u00eda una &#8220;condici\u00f3n muy clara para nosotros poner fin a las compras de activos netos&#8221;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p align=\"justify\"><span style=\"color: #007078;\"><img decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/1_2018-03-14.png\" width=\"512\" height=\"287\" \/><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">EE.<strong>UU.<\/strong><\/span><\/p>\n<p><span style=\"color: #007078;\">El presidente de Estados Unidos, Donald Trump, no mostr\u00f3 signos de suavizar su postura sobre los aranceles en un informe de Reuters el martes que el presidente est\u00e1 tratando de imponer aranceles sobre 60 mil millones de d\u00f3lares de importaciones chinas, apuntando a los sectores de tecnolog\u00eda y telecomunicaciones como parte de su campa\u00f1a para reducir los d\u00e9ficits comerciales.<\/span><\/p>\n<p><span style=\"color: #007078;\">Si bien los aranceles se destinar\u00edan principalmente a la tecnolog\u00eda de la informaci\u00f3n, la electr\u00f3nica de consumo y las telecomunicaciones, podr\u00edan ser mucho m\u00e1s amplios y la lista podr\u00eda llegar a alcanzar los 100 productos, dijo la fuente de la agencia de noticias.<\/span><\/p>\n<p><span style=\"color: #007078;\">La amenaza de aranceles adicionales en Estados Unidos podr\u00eda avivar los temores de una guerra comercial global y sopesar el apetito de los inversores por los activos de riesgo en un momento en que los inversores est\u00e1n preocupados por las turbulencias en Washington.<\/span><\/p>\n<p><span style=\"color: #007078;\">Despu\u00e9s de que Trump despidi\u00f3 al secretario de Estado Rex Tillerson el martes, algunos expertos han postulado que el presidente est\u00e1 allanando el camino para pol\u00edticas comerciales y fiscales m\u00e1s estrictas.<\/span><\/p>\n<p><span style=\"color: #007078;\">La eliminaci\u00f3n de Tillerson asust\u00f3 a los inversores burs\u00e1tiles el martes con los tres principales puntos de referencia de EE. UU. que terminaron en n\u00fameros rojos. Esas p\u00e9rdidas se extendieron a las acciones asi\u00e1ticas el mi\u00e9rcoles.<\/span><\/p>\n<p><span style=\"color: #007078;\">Sin embargo, los futuros de acciones de EE. UU. realizaron una recuperaci\u00f3n el mi\u00e9rcoles, apuntando a una apertura m\u00e1s alta en Wall Street. A las 5:55 AM ET (9: 55GMT), los futuros Dow Jones subieron 91 puntos, o 0,36 %, los futuros S &amp; P 500 subieron 8 puntos, o 0,30 %, mientras que los futuros del Nasdaq 100 subieron 30 puntos, o 0,42 %.<\/span><\/p>\n<p><span style=\"color: #007078;\">En el calendario econ\u00f3mico, los participantes del mercado se centrar\u00e1n en la publicaci\u00f3n de las ventas minoristas del Departamento de Comercio para el mes de febrero a las 8:30 a.m. ET (12: 30GMT).<\/span><\/p>\n<p><span style=\"color: #007078;\">El pron\u00f3stico del consenso es que el informe mostrar\u00e1 que las ventas minoristas subieron un 0,3 % el mes pasado, retrocediendo luego de una ca\u00edda del 0,3 % en enero.<\/span><\/p>\n<p><span style=\"color: #007078;\">Tambi\u00e9n se pronostica que las ventas principales subir\u00e1n un 0,3 %, luego de mantenerse planas un mes antes.<\/span><\/p>\n<p><span style=\"color: #007078;\">El aumento de las ventas minoristas a lo largo del tiempo se correlaciona con un mayor crecimiento econ\u00f3mico, mientras que las ventas m\u00e1s d\u00e9biles indican una econom\u00eda en declive. El gasto del consumidor representa hasta el 70 % del crecimiento econ\u00f3mico de EE. UU.<\/span><\/p>\n<p><span style=\"color: #007078;\">Al mismo tiempo, el mi\u00e9rcoles y antes de la decisi\u00f3n de la Reserva Federal sobre las tasas de inter\u00e9s programadas para el 21 de marzo, los inversores vigilar\u00e1n la inflaci\u00f3n a nivel mayorista.<\/span><\/p>\n<p><span style=\"color: #007078;\">Seg\u00fan lo medido por el \u00edndice de precios al productor, se espera que la inflaci\u00f3n mayorista se haya enfriado a 0,1 % en febrero desde 0,4 % en el mes anterior. La desaceleraci\u00f3n esperada en la inflaci\u00f3n mayorista se produce a pesar de la \u00faltima encuesta ISM que muestra que los fabricantes vieron aumentar los costos de los insumos al ritmo m\u00e1s r\u00e1pido en siete a\u00f1os.<\/span><\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/wp-content\/uploads\/2020\/07\/2_2018-03-14.png\" width=\"464\" height=\"366\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/3_2018-03-14.png\" width=\"461\" height=\"320\" \/><br \/>\n<span style=\"color: #007078;\">Los futuros de Wall Street marcan una tendencia alcista.<\/span><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/wp-content\/uploads\/2020\/07\/4_2018-03-14.png\" width=\"417\" height=\"90\" \/><br \/>\n<span style=\"color: #007078;\"><strong>RESUMEN DE MERCADO<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/5_2018-03-14.png\" width=\"512\" height=\"261\" \/><\/p>\n<p><span style=\"color: #007078;\"><strong>PETR\u00d3LEO<\/strong><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Se espera que la OPEP publique su informe mensual el mi\u00e9rcoles a las 7:20 AM ET que describir\u00e1 sus estimaciones sobre el crecimiento y la producci\u00f3n de la demanda mundial de petr\u00f3leo.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Se espera que la producci\u00f3n no perteneciente a la OPEP capte la atenci\u00f3n de los inversores adicionales despu\u00e9s de que el c\u00e1rtel petrolero estimara para sus rivales fuera del grupo en su informe anterior. Los EE. UU. constituyeron m\u00e1s de la mitad de la revisi\u00f3n al alza de la OPEP.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Los inversores tambi\u00e9n estaban atentos a se\u00f1ales de que las t\u00e1cticas de pol\u00edtica exterior m\u00e1s duras de Trump podr\u00edan influir en los mercados petroleros.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Un nuevo lote de datos de inventario, mientras tanto, de la Administraci\u00f3n de Informaci\u00f3n de Energ\u00eda (EIA) el mi\u00e9rcoles a las 10:30 a.m. ET se espera que muestre que las reservas de crudo de Estados Unidos aumentaron por tercera semana consecutiva.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Los analistas pronosticaron que los inventarios de crudo aumentaron en alrededor de 2.023 millones de barriles en la semana que finaliz\u00f3 el 9 de marzo.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">El martes por la noche, el American Petroleum Institute public\u00f3 sus datos que muestran que los inventarios de crudo hab\u00edan crecido en 1,2 millones de barriles en comparaci\u00f3n con las expectativas de una construcci\u00f3n de 1,5 millones de barriles.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Los futuros del petr\u00f3leo crudo de Estados Unidos subieron un 0,33 % a 60,91 d\u00f3lares a las 5:57 a.m. ET (9:57 GMT), mientras que el petr\u00f3leo Brent gan\u00f3 un 0,25 % a 64,80 d\u00f3lares.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large\" src=\"https:\/\/www.lyntik.co\/wp-content\/uploads\/2020\/07\/6_2018-03-14.png\" width=\"512\" height=\"348\" \/><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Contenido generado por Valora Inversiones, nuestros expertos en informaci\u00f3n de valor.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #007078;\">Fuente:\u00a0<a href=\"https:\/\/www.grupovalora.com.co\/\">www.grupovalora.com.co<\/a><\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>ASIA Las principales bolsas de valores de la regi\u00f3n Asia-Pac\u00edfico cerraron este mi\u00e9rcoles a la baja, ante los temores de un cambio en la pol\u00edtica [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-4881","post","type-post","status-publish","format-standard","hentry","category-finanzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU. - Blog lyntik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU. - Blog lyntik\" \/>\n<meta property=\"og:description\" content=\"ASIA Las principales bolsas de valores de la regi\u00f3n Asia-Pac\u00edfico cerraron este mi\u00e9rcoles a la baja, ante los temores de un cambio en la pol\u00edtica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog lyntik\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-14T15:16:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T17:29:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg\" \/>\n<meta name=\"author\" content=\"lyntik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lyntik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/\"},\"author\":{\"name\":\"lyntik\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"headline\":\"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU.\",\"datePublished\":\"2018-03-14T15:16:28+00:00\",\"dateModified\":\"2023-09-18T17:29:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/\"},\"wordCount\":1518,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-03-14.jpg\",\"articleSection\":[\"Finanzas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/\",\"name\":\"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU. - Blog lyntik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-03-14.jpg\",\"datePublished\":\"2018-03-14T15:16:28+00:00\",\"dateModified\":\"2023-09-18T17:29:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-03-14.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lyntik.co\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/2018-03-14.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/2018\\\/03\\\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/\",\"name\":\"Blog lyntik\",\"description\":\"Blog lyntik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/#\\\/schema\\\/person\\\/a78c35fd259c928e37caf37e643097ca\",\"name\":\"lyntik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076\",\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076\",\"contentUrl\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076\",\"caption\":\"lyntik\"},\"url\":\"https:\\\/\\\/lyntik.co\\\/blog\\\/author\\\/lyntik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU. - Blog lyntik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/","og_locale":"es_ES","og_type":"article","og_title":"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU. - Blog lyntik","og_description":"ASIA Las principales bolsas de valores de la regi\u00f3n Asia-Pac\u00edfico cerraron este mi\u00e9rcoles a la baja, ante los temores de un cambio en la pol\u00edtica [&hellip;]","og_url":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/","og_site_name":"Blog lyntik","article_published_time":"2018-03-14T15:16:28+00:00","article_modified_time":"2023-09-18T17:29:05+00:00","og_image":[{"url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg","type":"","width":"","height":""}],"author":"lyntik","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lyntik","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#article","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/"},"author":{"name":"lyntik","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"headline":"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU.","datePublished":"2018-03-14T15:16:28+00:00","dateModified":"2023-09-18T17:29:05+00:00","mainEntityOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/"},"wordCount":1518,"commentCount":0,"image":{"@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg","articleSection":["Finanzas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/","url":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/","name":"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU. - Blog lyntik","isPartOf":{"@id":"https:\/\/lyntik.co\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#primaryimage"},"image":{"@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg","datePublished":"2018-03-14T15:16:28+00:00","dateModified":"2023-09-18T17:29:05+00:00","author":{"@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca"},"breadcrumb":{"@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#primaryimage","url":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg","contentUrl":"https:\/\/www.lyntik.co\/blog\/wp-content\/uploads\/2020\/07\/2018-03-14.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lyntik.co\/blog\/2018\/03\/bolsas-mundiales-mixtas-luego-del-despido-del-secretario-estado-ee-uu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lyntik.co\/blog\/"},{"@type":"ListItem","position":2,"name":"Bolsas mundiales mixtas, luego del despido del secretario de Estado de EE. UU."}]},{"@type":"WebSite","@id":"https:\/\/lyntik.co\/blog\/#website","url":"https:\/\/lyntik.co\/blog\/","name":"Blog lyntik","description":"Blog lyntik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyntik.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lyntik.co\/blog\/#\/schema\/person\/a78c35fd259c928e37caf37e643097ca","name":"lyntik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076","url":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076","contentUrl":"https:\/\/lyntik.co\/blog\/wp-content\/litespeed\/avatar\/c22878f2154a145b0543e46682f3265f.jpg?ver=1778211076","caption":"lyntik"},"url":"https:\/\/lyntik.co\/blog\/author\/lyntik\/"}]}},"_links":{"self":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/4881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/comments?post=4881"}],"version-history":[{"count":1,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/4881\/revisions"}],"predecessor-version":[{"id":5648,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/posts\/4881\/revisions\/5648"}],"wp:attachment":[{"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/media?parent=4881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/categories?post=4881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyntik.co\/blog\/wp-json\/wp\/v2\/tags?post=4881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}